{"id":41388,"date":"2025-09-14T13:55:39","date_gmt":"2025-09-14T18:55:39","guid":{"rendered":"https:\/\/olimpicocol.co\/web\/?p=41388"},"modified":"2025-09-15T12:29:29","modified_gmt":"2025-09-15T17:29:29","slug":"colombia-se-movilizo-en-defensa-del-deporte","status":"publish","type":"post","link":"https:\/\/olimpicocol.co\/web\/colombia-se-movilizo-en-defensa-del-deporte\/","title":{"rendered":"Colombia se moviliz\u00f3 en defensa del deporte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este domingo 14 de septiembre, directivos, deportistas y ciudadanos participaron en una gran jornada de movilizaci\u00f3n nacional en favor del deporte, liderada por el sindicato del <strong>Ministerio del Deporte<\/strong>, Asminded, y respaldada por el <strong>Comit\u00e9 Ol\u00edmpico Colombiano<\/strong>.<br><br>La iniciativa, que llev\u00f3 como lema: \u201cS\u00ed al deporte, no al recorte\u201d, reuni\u00f3 a miles de colombianos en las diferentes ciudades del pa\u00eds, con el prop\u00f3sito de resaltar la importancia de la actividad f\u00edsica, la recreaci\u00f3n y el aprovechamiento del tiempo libre como pilares de salud, bienestar y cohesi\u00f3n social.<br><br>Vestidos de prendas amarillas como s\u00edmbolo de uni\u00f3n y compromiso con el deporte, los participantes realizaron una movilizaci\u00f3n desde la <strong>Carrera S\u00e9ptima con Calle 67 <\/strong>en <strong>Bogot\u00e1<\/strong>. Adem\u00e1s, videos y fotograf\u00edas de las actividades deportivas fueron compartidas a trav\u00e9s de las redes sociales con el hashtag <strong>#SiAlDeporteNoAlRecorte<\/strong>.<br><br>\u201cHoy 14 de septiembre nuevamente el deporte se une para hacer un llamado al gobierno nacional, al Congreso de la Rep\u00fablica y a todas las personas que de una u otra manera tienen que ver con el presupuesto nacional. Esperamos que reconsideren el presupuesto porque lo que est\u00e1 proyectado para el 2026 es pr\u00e1cticamente para acabar con los sue\u00f1os de futuros j\u00f3venes que ven el deporte como una alternativa social, que ven el deporte, el futuro de un pa\u00eds\u201d, expres\u00f3 el presidente del <strong>Comit\u00e9 Ol\u00edmpico Colombiano<\/strong>, Ciro Solano Hurtado, tras la jornada de este domingo.<br><br>Y remarc\u00f3: \u201cPor la falta de recursos no se podr\u00edan hacer grandes eventos, no se podr\u00edan apoyar los deportistas, no se podr\u00edan contratar entrenadores a las personas que hacen parte de las ciencias aplicadas, m\u00e9dicos, fisioterapeutas y todas estas personas que son necesarias para dar resultados. Los programas institucionales del Ministerio del Deporte, como los Juegos Intercolegiados, que llegan a todo el territorio nacional\u201d.<br><br>Adem\u00e1s de la capital del pa\u00eds, desde las 9:00 de la ma\u00f1ana se llevaron a cabo encuentros en diferentes ciudades como <strong>Armenia<\/strong>, <strong>Cali<\/strong>, <strong>Medell\u00edn <\/strong>y <strong>Manizales<\/strong>. Dentro del espacio realizado en <strong>Bogot\u00e1<\/strong>, entre los atletas presentes se encontraba <strong>Carlos Ram\u00edrez<\/strong>, quien destac\u00f3: \u201cEs la primera vez que el deporte se une para marchar por un presupuesto digno para los deportistas. Un presupuesto que sea suficiente para mantener lo que tenemos y para poder so\u00f1ar con ni\u00f1os que quieren ser como nosotros o mejor que nosotros. El deporte es paz, tranquilidad, esperanza y eso es lo que necesita\u00a0el\u00a0pa\u00eds\u201d.<br><br>La jornada pac\u00edfica cerr\u00f3 con un llamado por parte de la comunidad deportiva colombiana al <strong>Gobierno Nacional <\/strong>para que proteja y fortalezca las inversiones en el sector, recordando que el deporte es un motor de transformaci\u00f3n social y desarrollo integral para el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo 14 de septiembre, directivos, deportistas y ciudadanos participaron en una gran jornada de movilizaci\u00f3n nacional en favor del deporte, liderada por el sindicato del Ministerio del Deporte, Asminded, y respaldada por el Comit\u00e9 Ol\u00edmpico Colombiano. La iniciativa, que llev\u00f3 como lema: \u201cS\u00ed al deporte, no al recorte\u201d, reuni\u00f3 a miles de colombianos en [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":41390,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[2127,83,108],"class_list":["post-41388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mas-noticias","tag-2127","tag-colombia","tag-comite-olimpico-colombiano"],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 19:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/posts\/41388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/comments?post=41388"}],"version-history":[{"count":1,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/posts\/41388\/revisions"}],"predecessor-version":[{"id":41391,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/posts\/41388\/revisions\/41391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/media\/41390"}],"wp:attachment":[{"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/media?parent=41388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/categories?post=41388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/olimpicocol.co\/web\/wp-json\/wp\/v2\/tags?post=41388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}